{"id":17,"count":61,"description":"","link":"https:\/\/medschool.vanderbilt.edu\/career-development\/tag\/career-options-government-research\/","name":"Career Options: Government Research","slug":"career-options-government-research","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medschool.vanderbilt.edu\/career-development\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medschool.vanderbilt.edu\/career-development\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medschool.vanderbilt.edu\/career-development\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medschool.vanderbilt.edu\/career-development\/wp-json\/wp\/v2\/posts?tags=17"},{"href":"https:\/\/medschool.vanderbilt.edu\/career-development\/wp-json\/wp\/v2\/pages?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}